{"id":1598,"date":"2022-11-29T16:48:38","date_gmt":"2022-11-29T21:48:38","guid":{"rendered":"https:\/\/librosdeoro.cafam.com.co\/libro2022\/?page_id=1598"},"modified":"2022-12-12T09:02:55","modified_gmt":"2022-12-12T14:02:55","slug":"palabras-del-director-de-cafam","status":"publish","type":"page","link":"https:\/\/librosdeoro.cafam.com.co\/libro2022\/palabras-del-director-de-cafam\/","title":{"rendered":"Palabras del Director de Cafam"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":5,"featured_media":1695,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-1598","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Palabras del Director de Cafam - Libros de Oro 2022<\/title>\n<meta name=\"description\" content=\"En nombre del Consejo Directivo, de los Colaboradores y en el m\u00edo propio les extiendo un cordial saludo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/librosdeoro.cafam.com.co\/libro2022\/palabras-del-director-de-cafam\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Palabras del Director de Cafam - Libros de Oro 2022\" \/>\n<meta property=\"og:description\" content=\"En nombre del Consejo Directivo, de los Colaboradores y en el m\u00edo propio les extiendo un cordial saludo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/librosdeoro.cafam.com.co\/libro2022\/palabras-del-director-de-cafam\/\" \/>\n<meta property=\"og:site_name\" content=\"Libros de Oro 2022\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-12T14:02:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/librosdeoro.cafam.com.co\/libro2022\/wp-content\/uploads\/sites\/10\/2022\/12\/R7Q9863-1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1707\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/librosdeoro.cafam.com.co\/libro2022\/palabras-del-director-de-cafam\/\",\"url\":\"https:\/\/librosdeoro.cafam.com.co\/libro2022\/palabras-del-director-de-cafam\/\",\"name\":\"Palabras del Director de Cafam - Libros de Oro 2022\",\"isPartOf\":{\"@id\":\"https:\/\/librosdeoro.cafam.com.co\/libro2022\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/librosdeoro.cafam.com.co\/libro2022\/palabras-del-director-de-cafam\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/librosdeoro.cafam.com.co\/libro2022\/palabras-del-director-de-cafam\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/librosdeoro.cafam.com.co\/libro2022\/wp-content\/uploads\/sites\/10\/2022\/12\/R7Q9863-1-scaled.jpg\",\"datePublished\":\"2022-11-29T21:48:38+00:00\",\"dateModified\":\"2022-12-12T14:02:55+00:00\",\"description\":\"En nombre del Consejo Directivo, de los Colaboradores y en el m\u00edo propio les extiendo un cordial saludo\",\"breadcrumb\":{\"@id\":\"https:\/\/librosdeoro.cafam.com.co\/libro2022\/palabras-del-director-de-cafam\/#breadcrumb\"},\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/librosdeoro.cafam.com.co\/libro2022\/palabras-del-director-de-cafam\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/librosdeoro.cafam.com.co\/libro2022\/palabras-del-director-de-cafam\/#primaryimage\",\"url\":\"https:\/\/librosdeoro.cafam.com.co\/libro2022\/wp-content\/uploads\/sites\/10\/2022\/12\/R7Q9863-1-scaled.jpg\",\"contentUrl\":\"https:\/\/librosdeoro.cafam.com.co\/libro2022\/wp-content\/uploads\/sites\/10\/2022\/12\/R7Q9863-1-scaled.jpg\",\"width\":1707,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/librosdeoro.cafam.com.co\/libro2022\/palabras-del-director-de-cafam\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/librosdeoro.cafam.com.co\/libro2022\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Palabras del Director de Cafam\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/librosdeoro.cafam.com.co\/libro2022\/#website\",\"url\":\"https:\/\/librosdeoro.cafam.com.co\/libro2022\/\",\"name\":\"Libros de Oro 2022\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/librosdeoro.cafam.com.co\/libro2022\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es-CO\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Palabras del Director de Cafam - Libros de Oro 2022","description":"En nombre del Consejo Directivo, de los Colaboradores y en el m\u00edo propio les extiendo un cordial saludo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/librosdeoro.cafam.com.co\/libro2022\/palabras-del-director-de-cafam\/","og_locale":"es_ES","og_type":"article","og_title":"Palabras del Director de Cafam - Libros de Oro 2022","og_description":"En nombre del Consejo Directivo, de los Colaboradores y en el m\u00edo propio les extiendo un cordial saludo","og_url":"https:\/\/librosdeoro.cafam.com.co\/libro2022\/palabras-del-director-de-cafam\/","og_site_name":"Libros de Oro 2022","article_modified_time":"2022-12-12T14:02:55+00:00","og_image":[{"width":1707,"height":2560,"url":"https:\/\/librosdeoro.cafam.com.co\/libro2022\/wp-content\/uploads\/sites\/10\/2022\/12\/R7Q9863-1-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/librosdeoro.cafam.com.co\/libro2022\/palabras-del-director-de-cafam\/","url":"https:\/\/librosdeoro.cafam.com.co\/libro2022\/palabras-del-director-de-cafam\/","name":"Palabras del Director de Cafam - Libros de Oro 2022","isPartOf":{"@id":"https:\/\/librosdeoro.cafam.com.co\/libro2022\/#website"},"primaryImageOfPage":{"@id":"https:\/\/librosdeoro.cafam.com.co\/libro2022\/palabras-del-director-de-cafam\/#primaryimage"},"image":{"@id":"https:\/\/librosdeoro.cafam.com.co\/libro2022\/palabras-del-director-de-cafam\/#primaryimage"},"thumbnailUrl":"https:\/\/librosdeoro.cafam.com.co\/libro2022\/wp-content\/uploads\/sites\/10\/2022\/12\/R7Q9863-1-scaled.jpg","datePublished":"2022-11-29T21:48:38+00:00","dateModified":"2022-12-12T14:02:55+00:00","description":"En nombre del Consejo Directivo, de los Colaboradores y en el m\u00edo propio les extiendo un cordial saludo","breadcrumb":{"@id":"https:\/\/librosdeoro.cafam.com.co\/libro2022\/palabras-del-director-de-cafam\/#breadcrumb"},"inLanguage":"es-CO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/librosdeoro.cafam.com.co\/libro2022\/palabras-del-director-de-cafam\/"]}]},{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/librosdeoro.cafam.com.co\/libro2022\/palabras-del-director-de-cafam\/#primaryimage","url":"https:\/\/librosdeoro.cafam.com.co\/libro2022\/wp-content\/uploads\/sites\/10\/2022\/12\/R7Q9863-1-scaled.jpg","contentUrl":"https:\/\/librosdeoro.cafam.com.co\/libro2022\/wp-content\/uploads\/sites\/10\/2022\/12\/R7Q9863-1-scaled.jpg","width":1707,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/librosdeoro.cafam.com.co\/libro2022\/palabras-del-director-de-cafam\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/librosdeoro.cafam.com.co\/libro2022\/"},{"@type":"ListItem","position":2,"name":"Palabras del Director de Cafam"}]},{"@type":"WebSite","@id":"https:\/\/librosdeoro.cafam.com.co\/libro2022\/#website","url":"https:\/\/librosdeoro.cafam.com.co\/libro2022\/","name":"Libros de Oro 2022","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/librosdeoro.cafam.com.co\/libro2022\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es-CO"}]}},"_links":{"self":[{"href":"https:\/\/librosdeoro.cafam.com.co\/libro2022\/wp-json\/wp\/v2\/pages\/1598","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/librosdeoro.cafam.com.co\/libro2022\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/librosdeoro.cafam.com.co\/libro2022\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/librosdeoro.cafam.com.co\/libro2022\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/librosdeoro.cafam.com.co\/libro2022\/wp-json\/wp\/v2\/comments?post=1598"}],"version-history":[{"count":2,"href":"https:\/\/librosdeoro.cafam.com.co\/libro2022\/wp-json\/wp\/v2\/pages\/1598\/revisions"}],"predecessor-version":[{"id":1600,"href":"https:\/\/librosdeoro.cafam.com.co\/libro2022\/wp-json\/wp\/v2\/pages\/1598\/revisions\/1600"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/librosdeoro.cafam.com.co\/libro2022\/wp-json\/wp\/v2\/media\/1695"}],"wp:attachment":[{"href":"https:\/\/librosdeoro.cafam.com.co\/libro2022\/wp-json\/wp\/v2\/media?parent=1598"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}